{"id":1464,"date":"2025-04-01T11:00:00","date_gmt":"2025-04-01T09:00:00","guid":{"rendered":"https:\/\/intellienergy.it\/?p=1464"},"modified":"2025-04-01T12:22:29","modified_gmt":"2025-04-01T10:22:29","slug":"listino-2025","status":"publish","type":"post","link":"https:\/\/intellienergy.it\/it\/listino-2025\/","title":{"rendered":"Listino 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gentile Cliente,<br>con la presente vogliamo informarti che a partire da oggi, su nuove offerte ed ordini, sar\u00e0 applicato il listino 2025, valido fino al 31 marzo 2026.<br>Eventuali ordini gi\u00e0 emessi anche se non ancora evasi, conserveranno i prezzi del listino 2024.<br>Per richiedere una copia del listino, ti preghiamo di inviare una e-mail a <a href=\"mailto:commerciale@intellienergy.it\">commerciale@intellienergy.it<\/a> o di rivolgerti alla figura commerciale che ti segue.<br>Un cordiale saluto ed augurio di buon lavoro.<br><br><a href=\"https:\/\/www.linkedin.com\/company\/intellienergytech\/\" rel=\"noopener\">Intellienergy tech<\/a> S.r.l.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" data-id=\"1465\" src=\"https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-724x1024.png\" alt=\"\" class=\"wp-image-1465\" srcset=\"https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-724x1024.png 724w, https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-212x300.png 212w, https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-768x1086.png 768w, https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-1086x1536.png 1086w, https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1-1448x2048.png 1448w, https:\/\/intellienergy.it\/wp-content\/uploads\/2025\/04\/Listino-2025_HR-1.png 2480w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Gentile Cliente,con la presente vogliamo informarti che a partire da oggi, su nuove offerte ed ordini, sar\u00e0 applicato il listino 2025, valido fino al 31 marzo 2026.Eventuali ordini gi\u00e0 emessi anche se non ancora evasi, conserveranno i prezzi del listino 2024.Per richiedere una copia del listino, ti preghiamo di inviare una e-mail a commerciale@intellienergy.it o [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75],"tags":[],"class_list":["post-1464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"meta_box":[],"_links":{"self":[{"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/posts\/1464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/comments?post=1464"}],"version-history":[{"count":3,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/posts\/1464\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/posts\/1464\/revisions\/1470"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/media\/1468"}],"wp:attachment":[{"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/media?parent=1464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/categories?post=1464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/intellienergy.it\/it\/wp-json\/wp\/v2\/tags?post=1464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}